{"id":582,"date":"2023-06-20T21:12:46","date_gmt":"2023-06-20T18:12:46","guid":{"rendered":"https:\/\/artisus-project.eu\/?page_id=582"},"modified":"2023-06-20T21:14:14","modified_gmt":"2023-06-20T18:14:14","slug":"learners-innovation-activities","status":"publish","type":"page","link":"https:\/\/artisus-project.eu\/de\/learners-innovation-activities\/","title":{"rendered":"Learners Innovation Activities"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div class=\"vc_grid-container-wrapper vc_clearfix vc_grid-animation-fadeIn\">\n\t<div class=\"vc_grid-container vc_clearfix wpb_content_element vc_basic_grid\" data-initial-loading-animation=\"fadeIn\" data-vc-grid-settings=\"{&quot;page_id&quot;:582,&quot;style&quot;:&quot;all&quot;,&quot;action&quot;:&quot;vc_get_vc_grid_data&quot;,&quot;shortcode_id&quot;:&quot;1687284821153-a7dafb32-ae03-10&quot;,&quot;tag&quot;:&quot;vc_basic_grid&quot;}\" data-vc-request=\"https:\/\/artisus-project.eu\/wp-admin\/admin-ajax.php\" data-vc-post-id=\"582\" data-vc-public-nonce=\"84b21ca46d\">\n\t\t<style data-type=\"vc_shortcodes-custom-css\">.vc_custom_1419240516480{background-color: #f9f9f9 !important;}<\/style><ul class=\"vc_grid-filter vc_clearfix vc_grid-filter-default vc_grid-filter-size-md vc_grid-filter-center vc_grid-filter-color-grey\" data-vc-grid-filter=\"category\"><li class=\"vc_active vc_grid-filter-item\"><span data-vc-grid-filter-value=\"*\">Alle<\/span><\/li><li class=\"vc_grid-filter-item\"><span data-vc-grid-filter-value=\".vc_grid-term-18\">Germany<\/span><\/li><li class=\"vc_grid-filter-item\"><span data-vc-grid-filter-value=\".vc_grid-term-16\">Greece<\/span><\/li><li class=\"vc_grid-filter-item\"><span data-vc-grid-filter-value=\".vc_grid-term-19\">Italy<\/span><\/li><li class=\"vc_grid-filter-item\"><span data-vc-grid-filter-value=\".vc_grid-term-17\">Slovenia<\/span><\/li><\/ul><div class=\"vc_grid-filter-select vc_grid-filter-center vc_grid-filter-color-grey\" data-vc-grid-filter-select=\"category\"><div class=\"vc_grid-styled-select\"><select data-filter=\"category\"><option class=\"vc_active\" value=\"*\">Alle&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/option><option value=\".vc_grid-term-18\">Germany&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/option><option value=\".vc_grid-term-16\">Greece&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/option><option value=\".vc_grid-term-19\">Italy&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/option><option value=\".vc_grid-term-17\">Slovenia&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/option><\/select><i class=\"vc_arrow-icon-navicon\"><\/i>\n\t\t<\/div>\n\t<\/div><div class=\"vc_grid vc_row vc_grid-gutter-30px vc_pageable-wrapper vc_hook_hover\" data-vc-pageable-content=\"true\"><div class=\"vc_pageable-slide-wrapper vc_clearfix\" data-vc-grid-content=\"true\"><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-17\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/MG_6858-1024x750.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/group-exhibition-new-life\/\" title=\"GROUP EXHIBITION &#8211; NEW LIFE\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/MG_6858-1024x750.jpg\" class=\"vc_gitem-zone-img\" alt=\"MG 6858\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >GROUP EXHIBITION &#8211; NEW LIFE<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >After the February attack on Ukraine, many [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/group-exhibition-new-life\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-17\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/Jasna-Gabrovsek-1024x536.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/jasna-gabrovsek-heroines-workshop\/\" title=\"Jasna Gabrov\u0161ek &#8211; Heroines! Workshop\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/Jasna-Gabrovsek-1024x536.jpg\" class=\"vc_gitem-zone-img\" alt=\"Jasna Gabrov\u0161ek\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Jasna Gabrov\u0161ek &#8211; Heroines! Workshop<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >About the learner: Jasna pursued a degree [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/jasna-gabrovsek-heroines-workshop\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-17\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/e__MG_1756-1024x682.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/camilo-acosta-mendoza-cumbia-workshop\/\" title=\"Camilo Acosta Mendoza &#8211; Cumbia Workshop\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/e__MG_1756-1024x682.jpg\" class=\"vc_gitem-zone-img\" alt=\"e MG 1756\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Camilo Acosta Mendoza &#8211; Cumbia Workshop<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >Camilo Acosta Mendoza was born in Colombia [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/camilo-acosta-mendoza-cumbia-workshop\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-17\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/2_cirkusarija_logatec_2-1024x1024.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/markos-teklu-camilo-acosta-mendosa-circusstuff\/\" title=\"Markos Teklu &#038; Camilo Acosta Mendosa &#8211; CircusStuff\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/2_cirkusarija_logatec_2-1024x1024.jpg\" class=\"vc_gitem-zone-img\" alt=\"2 cirkusarija logatec 2\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Markos Teklu &#038; Camilo Acosta Mendosa &#8211; CircusStuff<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >About the learners: Markos, originally from Eritrea, [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/markos-teklu-camilo-acosta-mendosa-circusstuff\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-17\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/105336-1024x609.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/basma-orwa-atanasovski-international-mediterranean-day-concert\/\" title=\"Basma &#8211; Orwa &#8211; Atanasovski: International Mediterranean Day Concert\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/105336-1024x609.jpg\" class=\"vc_gitem-zone-img\" alt=\"105336\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Basma &#8211; Orwa &#8211; Atanasovski: International Mediterranean Day Concert<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >About the trio: Atanasovski, Basma, and Orwa [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/basma-orwa-atanasovski-international-mediterranean-day-concert\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-17\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/SLOVENIA-5-1024x682.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/iuliia-doroshenko-bucha-slovenia\/\" title=\"Iuliia Doroshenko: Bucha &#038; Slovenia\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/SLOVENIA-5-1024x682.jpg\" class=\"vc_gitem-zone-img\" alt=\"SLOVENIA 5\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Iuliia Doroshenko: Bucha &#038; Slovenia<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >\u00a0She was born in Kyiv in 1975. [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/iuliia-doroshenko-bucha-slovenia\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-17\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/Oryna-Fedotova-1-764x1024.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/oryna-fedotova-war-and-peace\/\" title=\"Oryna Fedotova &#8211; War and Peace\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/Oryna-Fedotova-1-764x1024.jpg\" class=\"vc_gitem-zone-img\" alt=\"Oryna Fedotova 1\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Oryna Fedotova &#8211; War and Peace<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >About the artist: Oryna Fedotova was born [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/oryna-fedotova-war-and-peace\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-17\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/10_Marharyta-Kalyuzhna_6MJ2473-766x1024.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/marharyta-kalyuzhna-where-is-home\/\" title=\"Marharyta Kalyuzhna &#8211; Where is Home\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/10_Marharyta-Kalyuzhna_6MJ2473-766x1024.jpg\" class=\"vc_gitem-zone-img\" alt=\"10 Marharyta Kalyuzhna 6MJ2473\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Marharyta Kalyuzhna &#8211; Where is Home<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >Marharyta Kalyuzhna - In Anticipation (of Victory [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/marharyta-kalyuzhna-where-is-home\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-17\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/tetyana-exhibition-1024x791.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/tetyana-donets-savko-illustrations-for-childrens-book\/\" title=\"Tetyana Donets-Savko &#8211;  Illustrations for Children&#8217;s Book\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/tetyana-exhibition-1024x791.jpg\" class=\"vc_gitem-zone-img\" alt=\"tetyana exhibition\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Tetyana Donets-Savko &#8211;  Illustrations for Children&#8217;s Book<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >About the learner: Tetyana Donets-Savko, born in [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/tetyana-donets-savko-illustrations-for-childrens-book\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-17\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/Anna-Miklashevich-3-1024x718.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/anna-miklashevich-dream-vision\/\" title=\"Anna Miklashevich &#8211; Dream Vision\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/Anna-Miklashevich-3-1024x718.jpg\" class=\"vc_gitem-zone-img\" alt=\"Anna Miklashevich 3\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Anna Miklashevich &#8211; Dream Vision<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >About the learner: Anna Miklashevich is a [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/anna-miklashevich-dream-vision\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-17\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/Zoia-Khivrenko-War-683x1024.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/zoia-khivrenko-war\/\" title=\"Zoia Khivrenko &#8211; War\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/Zoia-Khivrenko-War-683x1024.jpg\" class=\"vc_gitem-zone-img\" alt=\"Zoia Khivrenko War\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Zoia Khivrenko &#8211; War<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >About the learner: Zoia Khivrenko &nbsp; Zoia [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/zoia-khivrenko-war\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-17\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/104719-1024x574.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/terminus\/\" title=\"Terminus\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/104719-1024x574.jpg\" class=\"vc_gitem-zone-img\" alt=\"104719\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Terminus<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >About the learner: &nbsp; The author has [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/terminus\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-17\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/104552-1024x581.png') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/hakim-asnabla-extended-eyes\/\" title=\"Hakim Asnabla &#8211; Extended Eyes\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/104552-1024x581.png\" class=\"vc_gitem-zone-img\" alt=\"104552\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Hakim Asnabla &#8211; Extended Eyes<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >About the learner: Abdelhakim Asnabla was born [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/hakim-asnabla-extended-eyes\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-17\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/DSC08954-Edit-683x1024.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/nino-bektashashvili-lasha-the-artist-georgian-diaspora\/\" title=\"Nino Bektashashvili &#8211; Lasha the Artist &#038; Georgian Diaspora\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/DSC08954-Edit-683x1024.jpg\" class=\"vc_gitem-zone-img\" alt=\"DSC08954 Edit\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Nino Bektashashvili &#8211; Lasha the Artist &#038; Georgian Diaspora<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >About the learner: Nino Bektashashvili is a [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/nino-bektashashvili-lasha-the-artist-georgian-diaspora\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-17\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/103930-1024x577.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/anna-miklashevich-uartist\/\" title=\"Anna Miklashevich &#8211; Uartist\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/103930-1024x577.jpg\" class=\"vc_gitem-zone-img\" alt=\"103930\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Anna Miklashevich &#8211; Uartist<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >About the learner: A Ukrainian artist who [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/anna-miklashevich-uartist\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-19\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/1.-Flavio-Mandolini-and-Paolo-D-Nicola_creative-writing-workshop-Rodari-Model_320891758_1106613126704971_8563985081269642000_n-Athena-DOrazio-1024x576.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/flavio-mandolini-and-paolo-di-nicola-creative-writing-workshop-rodari-model\/\" title=\"Flavio Mandolini and Paolo Di Nicola &#8211; Creative Writing Workshop\/ Rodari Model\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/1.-Flavio-Mandolini-and-Paolo-D-Nicola_creative-writing-workshop-Rodari-Model_320891758_1106613126704971_8563985081269642000_n-Athena-DOrazio-1024x576.jpg\" class=\"vc_gitem-zone-img\" alt=\"1. Flavio Mandolini and Paolo D Nicola creative writing workshop Rodari Model 320891758 1106613126704971 8563985081269642000 n Athena D'Orazio\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Flavio Mandolini and Paolo Di Nicola &#8211; Creative Writing Workshop\/ Rodari Model<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><p>About the learners\u00a0: Flavio is a graduate [&hellip;]<\/p>\n<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/flavio-mandolini-and-paolo-di-nicola-creative-writing-workshop-rodari-model\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-19\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/2.-Simone-Pacini-and-Carolina-Truzzi-Building-the-Landscape_Teen_Networking-Event_simone-pacini-1024x859.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/simone-pacini-and-carolina-truzzi-building-landascapes-teen-on-line-workshop\/\" title=\"Simone Pacini and Carolina Truzzi &#8211; Building Landascapes- Teen: On line Workshop\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/2.-Simone-Pacini-and-Carolina-Truzzi-Building-the-Landscape_Teen_Networking-Event_simone-pacini-1024x859.jpg\" class=\"vc_gitem-zone-img\" alt=\"2. Simone Pacini and Carolina Truzzi Building the Landscape Teen Networking Event simone pacini\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Simone Pacini and Carolina Truzzi &#8211; Building Landascapes- Teen: On line Workshop<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><p>About the learners: Simone Pacini and Carolina [&hellip;]<\/p>\n<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/simone-pacini-and-carolina-truzzi-building-landascapes-teen-on-line-workshop\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-19\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/3.-Francesco-DAlessandro_Cineforum-Kids_320508199_500595378804760_5398439388514658228_n-Athena-DOrazio-1024x768.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/francesco-dalessandro-citizens-wishes-and-cineforum-kids\/\" title=\"Francesco D&#8217;Alessandro &#8211; Citizens&#8217; wishes and Cineforum Kids\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/3.-Francesco-DAlessandro_Cineforum-Kids_320508199_500595378804760_5398439388514658228_n-Athena-DOrazio-1024x768.jpg\" class=\"vc_gitem-zone-img\" alt=\"3. Francesco D'Alessandro Cineforum Kids 320508199 500595378804760 5398439388514658228 n Athena D'Orazio\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Francesco D&#8217;Alessandro &#8211; Citizens&#8217; wishes and Cineforum Kids<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><p>About the learner: Francesco D&#8217;Alessandro is a [&hellip;]<\/p>\n<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/francesco-dalessandro-citizens-wishes-and-cineforum-kids\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-19\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/4.-Fabio-Angelozzi-\u2013-Notes-of-social-justice-1024x576.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/fabio-angelozzi-notes-of-social-justice\/\" title=\"Fabio Angelozzi &#8211; Notes of social justice\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/4.-Fabio-Angelozzi-\u2013-Notes-of-social-justice-1024x576.jpg\" class=\"vc_gitem-zone-img\" alt=\"4. Fabio Angelozzi \u2013 Notes of social justice\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Fabio Angelozzi &#8211; Notes of social justice<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><p>About the learner: The Italian participant, Fabio, [&hellip;]<\/p>\n<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/fabio-angelozzi-notes-of-social-justice\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-19\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/5Chiara-Ballone_Poetica-mente_-larte-come-rinascita_317244272_10227963143132013_2226215203681204836_n-Athena-DOrazio-1024x461.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/chiara-ballone-poetica-mente-larte-come-rinascita-percorsi-esperienziali-tra-arte-e-psicologia-poetics-mind-art-as-rebirth-experiential-paths-between-art-and-psychology\/\" title=\"Chiara Ballone &#8211; Poetica-mente: l&#8217;arte come rinascita. Percorsi esperienziali tra arte e psicologia.\/ Poetics-mind: art as rebirth. Experiential paths between art and psychology.\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/5Chiara-Ballone_Poetica-mente_-larte-come-rinascita_317244272_10227963143132013_2226215203681204836_n-Athena-DOrazio-1024x461.jpg\" class=\"vc_gitem-zone-img\" alt=\"5Chiara Ballone Poetica mente l'arte come rinascita 317244272 10227963143132013 2226215203681204836 n Athena D'Orazio\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Chiara Ballone &#8211; Poetica-mente: l&#8217;arte come rinascita. Percorsi esperienziali tra arte e psicologia.\/ Poetics-mind: art as rebirth. Experiential paths between art and psychology.<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><p>About the learner: Chiara Ballone is a [&hellip;]<\/p>\n<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/chiara-ballone-poetica-mente-larte-come-rinascita-percorsi-esperienziali-tra-arte-e-psicologia-poetics-mind-art-as-rebirth-experiential-paths-between-art-and-psychology\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-19\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/6.-Dolus_Patrizia-di-Nella_321443640_692799028887281_4914981089291999638_n-Athena-DOrazio-1024x576.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/patrizia-di-nella-dolus\/\" title=\"Patrizia di Nella &#8211; Dolus\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/6.-Dolus_Patrizia-di-Nella_321443640_692799028887281_4914981089291999638_n-Athena-DOrazio-1024x576.jpg\" class=\"vc_gitem-zone-img\" alt=\"6. Dolus Patrizia di Nella 321443640 692799028887281 4914981089291999638 n Athena D'Orazio\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Patrizia di Nella &#8211; Dolus<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><p>About the learner: Patrizia Di Nella is [&hellip;]<\/p>\n<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/patrizia-di-nella-dolus\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-19\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/plugins\/js_composer\/assets\/vc\/vc_gitem_image.png') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/ermes-angelozzi-i-have-a-dream-to-live-safe\/\" title=\"Ermes Angelozzi &#8211; I Have a dream to live safe\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/plugins\/js_composer\/assets\/vc\/vc_gitem_image.png\" class=\"vc_gitem-zone-img\" alt=\"\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Ermes Angelozzi &#8211; I Have a dream to live safe<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><p>About the learner: The Italian participant, Ermes [&hellip;]<\/p>\n<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/ermes-angelozzi-i-have-a-dream-to-live-safe\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-19\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/8.Tania-Troiani-Museum-digitalisation-Party_Immagine-WhatsApp-2022-12-22-ore-10.59.45-Athena-DOrazio-1024x859.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/tania-troiani-museum-digitalisation-party\/\" title=\"Tania Troiani &#8211; Museum digitalisation Party\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/8.Tania-Troiani-Museum-digitalisation-Party_Immagine-WhatsApp-2022-12-22-ore-10.59.45-Athena-DOrazio-1024x859.jpg\" class=\"vc_gitem-zone-img\" alt=\"8.Tania Troiani Museum digitalisation Party Immagine WhatsApp 2022 12 22 ore 10.59.45 Athena D'Orazio\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Tania Troiani &#8211; Museum digitalisation Party<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><p>About the learner: Tania Troiani she has [&hellip;]<\/p>\n<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/tania-troiani-museum-digitalisation-party\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-19\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/9.Gianni-Bona_Immagine-WhatsApp-2022-12-31-ore-10.58.09-Athena-DOrazio-1024x461.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/gianni-bona-il-cenacolo-di-michetti\/\" title=\"Gianni Bona &#8211; Il Cenacolo di Michetti\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/9.Gianni-Bona_Immagine-WhatsApp-2022-12-31-ore-10.58.09-Athena-DOrazio-1024x461.jpg\" class=\"vc_gitem-zone-img\" alt=\"9.Gianni Bona Immagine WhatsApp 2022 12 31 ore 10.58.09 Athena D'Orazio\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Gianni Bona &#8211; Il Cenacolo di Michetti<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><p>Gianni Bona created a tourist-cultural trail inspired [&hellip;]<\/p>\n<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/gianni-bona-il-cenacolo-di-michetti\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-19\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/10.-Mara-Calcagni-and-Raffaella-Vollaro-Il-Filo-del-Quarticciolo_316545471_10159479374963111_988424090897911954_n-Athena-DOrazio-1-740x1024.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/mara-calcagni-and-raffaella-vollaro-il-filo-del-quarticciolo\/\" title=\"Mara Calcagni and Raffaella Vollaro &#8211; Il Filo del Quarticciolo\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/10.-Mara-Calcagni-and-Raffaella-Vollaro-Il-Filo-del-Quarticciolo_316545471_10159479374963111_988424090897911954_n-Athena-DOrazio-1-740x1024.jpg\" class=\"vc_gitem-zone-img\" alt=\"10. Mara Calcagni and Raffaella Vollaro Il Filo del Quarticciolo 316545471 10159479374963111 988424090897911954 n Athena D'Orazio (1)\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Mara Calcagni and Raffaella Vollaro &#8211; Il Filo del Quarticciolo<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><p>About the learners: Raffaella Vollaro graduated in [&hellip;]<\/p>\n<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/mara-calcagni-and-raffaella-vollaro-il-filo-del-quarticciolo\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-19\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/103144-1024x575.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/marta-malsegna-paradiso-urbano\/\" title=\"Marta Malsegna &#8211; Paradiso Urbano\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/103144-1024x575.jpg\" class=\"vc_gitem-zone-img\" alt=\"103144\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Marta Malsegna &#8211; Paradiso Urbano<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >About the learner: Marta Malsegna carried out [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/marta-malsegna-paradiso-urbano\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-16\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/IMG_20221008_015455-1024x768.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/niki-katsargyri-balomatou\/\" title=\"Niki Katsargyri \u2013 Balomatou\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/IMG_20221008_015455-1024x768.jpg\" class=\"vc_gitem-zone-img\" alt=\"IMG 20221008 015455\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Niki Katsargyri \u2013 Balomatou<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >Niki Katsargyri Niki Katsargyri creates jewelry, alternative [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/niki-katsargyri-balomatou\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-16\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/mexico-13-1024x686.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/constantino-ramon-papachatzis-pena-mexican-culture\/\" title=\"Constantino Ramon Papachatzis Pe\u00f1a \u2013 Mexican culture\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/mexico-13-1024x686.jpg\" class=\"vc_gitem-zone-img\" alt=\"Mexican Calavera\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Constantino Ramon Papachatzis Pe\u00f1a \u2013 Mexican culture<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >Ramon is originally from Mexico and studied [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/constantino-ramon-papachatzis-pena-mexican-culture\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-16\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/325292605_595441612328691_2440008492928684306_n-497x1024.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/sandro-ambrosio-looking-for-the-lost-wood-alla-ricerca-del-legno-perduto\/\" title=\"Sandro Ambrosio \u2013 \u201cLooking for the lost wood\u201d \/ \u201cAlla ricerca del legno perduto\u201d\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/325292605_595441612328691_2440008492928684306_n-497x1024.jpg\" class=\"vc_gitem-zone-img\" alt=\"325292605 595441612328691 2440008492928684306 n\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Sandro Ambrosio \u2013 \u201cLooking for the lost wood\u201d \/ \u201cAlla ricerca del legno perduto\u201d<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >Sandro Ambrosio Sandro Ambrosio is a 72-year-old [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/sandro-ambrosio-looking-for-the-lost-wood-alla-ricerca-del-legno-perduto\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-16\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/312234-1024x570.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/nastya-dukhovna-a-day-at-the-beach\/\" title=\"Nastya Dukhovna \u2013 A day at the beach\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/312234-1024x570.jpg\" class=\"vc_gitem-zone-img\" alt=\"312234\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Nastya Dukhovna \u2013 A day at the beach<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >Nastya Dukhovna Nastya, our Art is Us [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/nastya-dukhovna-a-day-at-the-beach\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-16\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/20220615_150734_defaced-1024x768.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/tanya-radchenko-vytynanka\/\" title=\"Tanya Radchenko \u2013 Vytynanka\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/20220615_150734_defaced-1024x768.jpg\" class=\"vc_gitem-zone-img\" alt=\"20220615 150734 defaced\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Tanya Radchenko \u2013 Vytynanka<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >Tanya Radchenko Tanya is a volunteer at [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/tanya-radchenko-vytynanka\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-16\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/image-4-1024x655.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/christina-argyriou-the-teacher-starter\/\" title=\"Christina Argyriou \u2013 The Teacher Starter\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/image-4-1024x655.jpg\" class=\"vc_gitem-zone-img\" alt=\"image (4)\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Christina Argyriou \u2013 The Teacher Starter<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >Christina Argyriou Christina Argyriou is a teacher [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/christina-argyriou-the-teacher-starter\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-16\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/eikona3-1024x739.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/kiki-linardou-paintings-on-canvas-untitled-project-2022\/\" title=\"Kiki Linardou &#8211; Paintings on Canvas: \u00abUntitled Project\u00bb 2022\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/eikona3-1024x739.jpg\" class=\"vc_gitem-zone-img\" alt=\"eikona3\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Kiki Linardou &#8211; Paintings on Canvas: \u00abUntitled Project\u00bb 2022<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >Kiki Linardou Kiki Linardou is a young [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/kiki-linardou-paintings-on-canvas-untitled-project-2022\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-16\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/1-3-1024x577.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/eleni-perrou-omouti-hope\/\" title=\"Eleni Perrou &#8211; Omouti \/ Hope\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/1-3-1024x577.jpg\" class=\"vc_gitem-zone-img\" alt=\"1 (3)\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Eleni Perrou &#8211; Omouti \/ Hope<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >Eleni Perrou Eleni Perrou is a public-school [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/eleni-perrou-omouti-hope\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-16\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/FB_IMG_1684252398596-1024x768.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/olia-rychagivska-archaeological-sites-visits-in-athens-for-the-ukrainian-community\/\" title=\"Olia Rychagivska- Archaeological sites&#8217; visits in Athens for the Ukrainian community\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/FB_IMG_1684252398596-1024x768.jpg\" class=\"vc_gitem-zone-img\" alt=\"FB IMG 1684252398596\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Olia Rychagivska- Archaeological sites&#8217; visits in Athens for the Ukrainian community<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >Olia Rychagivska Olia is a learner of [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/olia-rychagivska-archaeological-sites-visits-in-athens-for-the-ukrainian-community\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-16\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/21223-1024x578.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/rouin-muhammadi-the-story-of-the-greek-forum-of-refugees\/\" title=\"Rouin Muhammadi &#8211; The story of the Greek Forum of Refugees\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/21223-1024x578.jpg\" class=\"vc_gitem-zone-img\" alt=\"21223\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Rouin Muhammadi &#8211; The story of the Greek Forum of Refugees<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >Rouin Muhammadi Rouin Muhammadi, a 22-year-old undergraduate [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/rouin-muhammadi-the-story-of-the-greek-forum-of-refugees\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-16\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/FB_IMG_1684251895642-1024x692.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/oleksandra-novikova-vicinity\/\" title=\"Oleksandra Novikova &#8211; Vicinity\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/FB_IMG_1684251895642-1024x692.jpg\" class=\"vc_gitem-zone-img\" alt=\"FB IMG 1684251895642\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Oleksandra Novikova &#8211; Vicinity<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >Oleksandra Novikova Sasha, a humanitarian worker and [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/oleksandra-novikova-vicinity\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-16\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/IMG_20221010_161936-709x1024.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/iordanis-protogerakis-fluidity\/\" title=\"Iordanis Protogerakis \u2013 Fluidity\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/IMG_20221010_161936-709x1024.jpg\" class=\"vc_gitem-zone-img\" alt=\"IMG 20221010 161936\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Iordanis Protogerakis \u2013 Fluidity<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >Iordanis Protogerakis Iordanis Protogerakis, a 29-year-old cook, [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/iordanis-protogerakis-fluidity\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-16\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/IMG_20221007_2157357-1024x661.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/stamatis-kyriakos-my-identity-as-an-lgbtq-person\/\" title=\"Stamatis Kyriakos &#8211; My identity as an LGBTQ person\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/IMG_20221007_2157357-1024x661.jpg\" class=\"vc_gitem-zone-img\" alt=\"IMG 20221007 2157357\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Stamatis Kyriakos &#8211; My identity as an LGBTQ person<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >Stamatis Kiriakos &nbsp; Stamatis Kiriakos, a social [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/stamatis-kyriakos-my-identity-as-an-lgbtq-person\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-16\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/Social-Football-13-2-1024x683.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/mary-lazaridi-social-football\/\" title=\"Mary Lazaridi &#8211; Social Football\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/Social-Football-13-2-1024x683.jpg\" class=\"vc_gitem-zone-img\" alt=\"Social Football 13 2\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Mary Lazaridi &#8211; Social Football<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >Mary Lazaridi As a photographer with a [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/mary-lazaridi-social-football\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-16\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/9-1024x744.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/marina-gkavardina-love-without-borders\/\" title=\"Marina Gkavardina &#8211; Love Without Borders\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/9-1024x744.jpg\" class=\"vc_gitem-zone-img\" alt=\"9\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Marina Gkavardina &#8211; Love Without Borders<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >Marina Gkavardina Marina Gkavardina is an art [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/marina-gkavardina-love-without-borders\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-18\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/photo-4-2-copy-993x1024.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/the-project-body-painting-to-the-music-by-aleksandra-vagabonda\/\" title=\"The project &#8220;Body painting to the music&#8221; by Aleksandra Vagabonda\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/photo-4-2-copy-993x1024.jpg\" class=\"vc_gitem-zone-img\" alt=\"photo 4 (2) copy\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >The project &#8220;Body painting to the music&#8221; by Aleksandra Vagabonda<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >The project \"Body painting to the music\" [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/the-project-body-painting-to-the-music-by-aleksandra-vagabonda\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-18\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/photo-3-copy-990x1024.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/the-yoga-sessions-for-ukrainian-refugees-by-nastya-kuranda\/\" title=\"The Yoga-sessions for Ukrainian Refugees by Nastya Kuranda\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/photo-3-copy-990x1024.jpg\" class=\"vc_gitem-zone-img\" alt=\"photo 3 copy\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >The Yoga-sessions for Ukrainian Refugees by Nastya Kuranda<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >The Yoga-sessions for Ukrainian Refugees by Nastya [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/the-yoga-sessions-for-ukrainian-refugees-by-nastya-kuranda\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-18\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/photo-2-copy-1010x1024.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/the-musical-jam-sessions-by-izabela-modrzewska\/\" title=\"The Musical Jam Sessions by Izabela Modrzewska\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/photo-2-copy-1010x1024.jpg\" class=\"vc_gitem-zone-img\" alt=\"photo 2 copy\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >The Musical Jam Sessions by Izabela Modrzewska<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >The Musical Jam Sessions by Izabela Modrzewska, [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/the-musical-jam-sessions-by-izabela-modrzewska\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom vc_grid-term-18\"><div class=\"vc_grid-item-mini vc_clearfix\"><div class=\"vc_gitem-animated-block\" ><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-1-1 vc_gitem-is-link\" style=\"background-image: url('https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/photo-1-copy-997x1024.jpg') !important;\"><a href=\"https:\/\/artisus-project.eu\/de\/the-petrykivka-workshop-by-annah-mukhanova\/\" title=\"The Petrykivka-workshop by Annah Mukhanova\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img src=\"https:\/\/artisus-project.eu\/wp-content\/uploads\/2023\/06\/photo-1-copy-997x1024.jpg\" class=\"vc_gitem-zone-img\" alt=\"photo 1 copy\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240516480\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >The Petrykivka-workshop by Annah Mukhanova<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >The Petrykivka-workshop by Annah Mukhanova, as it [...]<\/p><\/div><div class=\"vc_btn3-container vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-color-juicy-pink\" a href=\"https:\/\/artisus-project.eu\/de\/the-petrykivka-workshop-by-annah-mukhanova\/\" title=\"Weiterlesen\">Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><\/div><\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"AlleGermanyGreeceItalySloveniaAlle&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Germany&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Greece&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Italy&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Slovenia&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; GROUP EXHIBITION &#8211; NEW LIFEAfter the [...]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-full.php","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/artisus-project.eu\/de\/wp-json\/wp\/v2\/pages\/582"}],"collection":[{"href":"https:\/\/artisus-project.eu\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/artisus-project.eu\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/artisus-project.eu\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/artisus-project.eu\/de\/wp-json\/wp\/v2\/comments?post=582"}],"version-history":[{"count":0,"href":"https:\/\/artisus-project.eu\/de\/wp-json\/wp\/v2\/pages\/582\/revisions"}],"wp:attachment":[{"href":"https:\/\/artisus-project.eu\/de\/wp-json\/wp\/v2\/media?parent=582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}